{"id":5548,"date":"2025-06-10T19:18:14","date_gmt":"2025-06-10T19:18:14","guid":{"rendered":"https:\/\/www.uniquewines.mx\/our-brands\/france\/joseph-drouhin\/macon-villages\/"},"modified":"2025-07-30T08:56:43","modified_gmt":"2025-07-30T08:56:43","slug":"macon-villages","status":"publish","type":"page","link":"https:\/\/www.uniquewines.mx\/en\/our-brands\/france\/joseph-drouhin\/macon-villages\/","title":{"rendered":"Macon Villages"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5548\" class=\"elementor elementor-5548 elementor-2335\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6906963a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6906963a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5422f712\" data-id=\"5422f712\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-175dc24a elementor-section-content-top elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"175dc24a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-5129d3b4\" data-id=\"5129d3b4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6dc9b45 elementor-widget elementor-widget-heading\" data-id=\"6dc9b45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.uniquewines.mx\/en\/our-brands\/france\/joseph-drouhin\/\">Joseph Drouhin<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1478ec5 elementor-widget elementor-widget-heading\" data-id=\"1478ec5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Macon Villages<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-707c67b8 elementor-widget elementor-widget-text-editor\" data-id=\"707c67b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 1\"><div class=\"section\">The wine&#8217;s color is bright and clear. On the nose, it is floral and fruity. On the palate, it is very frank and direct, as if you were biting into a grape. Fresh and light, with a very pleasant aftertaste.   <\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-01c10f1 elementor-widget elementor-widget-gallery\" data-id=\"01c10f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:5,&quot;sizes&quot;:[]},&quot;aspect_ratio&quot;:&quot;1:1&quot;,&quot;columns&quot;:3,&quot;columns_laptop&quot;:3,&quot;columns_mobile&quot;:3,&quot;gap_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:5,&quot;sizes&quot;:[]},&quot;lazyload&quot;:&quot;yes&quot;,&quot;gallery_layout&quot;:&quot;grid&quot;,&quot;columns_tablet&quot;:2,&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2025\/06\/I65A5012-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"01c10f1\" data-elementor-lightbox-title=\"I65A5012\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjI2MiwidXJsIjoiaHR0cHM6XC9cL3d3dy51bmlxdWV3aW5lcy5teFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDZcL0k2NUE1MDEyLXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiIwMWMxMGYxIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2025\/06\/I65A5012-200x300.jpg\" data-width=\"200\" data-height=\"300\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2025\/06\/Maison_Joseph_Drouhin_suite086-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"01c10f1\" data-elementor-lightbox-title=\"Maison_Joseph_Drouhin_suite086\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxMywidXJsIjoiaHR0cHM6XC9cL3d3dy51bmlxdWV3aW5lcy5teFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDZcL01haXNvbl9Kb3NlcGhfRHJvdWhpbl9zdWl0ZTA4Ni1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiMDFjMTBmMSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2025\/06\/Maison_Joseph_Drouhin_suite086-300x200.jpg\" data-width=\"300\" data-height=\"200\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2025\/06\/Maison_Joseph_Drouhin_suite064-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"01c10f1\" data-elementor-lightbox-title=\"Maison_Joseph_Drouhin_suite064\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxMiwidXJsIjoiaHR0cHM6XC9cL3d3dy51bmlxdWV3aW5lcy5teFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDZcL01haXNvbl9Kb3NlcGhfRHJvdWhpbl9zdWl0ZTA2NC1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiMDFjMTBmMSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2025\/06\/Maison_Joseph_Drouhin_suite064-300x200.jpg\" data-width=\"300\" data-height=\"200\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d30ed18 elementor-widget elementor-widget-button\" data-id=\"d30ed18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2025\/06\/M-con-Villages-2022.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-file-pdf\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M369.9 97.9L286 14C277 5 264.8-.1 252.1-.1H48C21.5 0 0 21.5 0 48v416c0 26.5 21.5 48 48 48h288c26.5 0 48-21.5 48-48V131.9c0-12.7-5.1-25-14.1-34zM332.1 128H256V51.9l76.1 76.1zM48 464V48h160v104c0 13.3 10.7 24 24 24h104v288H48zm250.2-143.7c-12.2-12-47-8.7-64.4-6.5-17.2-10.5-28.7-25-36.8-46.3 3.9-16.1 10.1-40.6 5.4-56-4.2-26.2-37.8-23.6-42.6-5.9-4.4 16.1-.4 38.5 7 67.1-10 23.9-24.9 56-35.4 74.4-20 10.3-47 26.2-51 46.2-3.3 15.8 26 55.2 76.1-31.2 22.4-7.4 46.8-16.5 68.4-20.1 18.9 10.2 41 17 55.8 17 25.5 0 28-28.2 17.5-38.7zm-198.1 77.8c5.1-13.7 24.5-29.5 30.4-35-19 30.3-30.4 35.7-30.4 35zm81.6-190.6c7.4 0 6.7 32.1 1.8 40.8-4.4-13.9-4.3-40.8-1.8-40.8zm-24.4 136.6c9.7-16.9 18-37 24.7-54.7 8.3 15.1 18.9 27.2 30.1 35.5-20.8 4.3-38.9 13.1-54.8 19.2zm131.6-5s-5 6-37.3-7.8c35.1-2.6 40.9 5.4 37.3 7.8z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Download Technical Sheet<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d986ba1 elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"d986ba1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/unique.doppelandganger.xyz\/wp-content\/uploads\/2025\/05\/HSM-bottle-shots.zip\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-file-pdf\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M369.9 97.9L286 14C277 5 264.8-.1 252.1-.1H48C21.5 0 0 21.5 0 48v416c0 26.5 21.5 48 48 48h288c26.5 0 48-21.5 48-48V131.9c0-12.7-5.1-25-14.1-34zM332.1 128H256V51.9l76.1 76.1zM48 464V48h160v104c0 13.3 10.7 24 24 24h104v288H48zm250.2-143.7c-12.2-12-47-8.7-64.4-6.5-17.2-10.5-28.7-25-36.8-46.3 3.9-16.1 10.1-40.6 5.4-56-4.2-26.2-37.8-23.6-42.6-5.9-4.4 16.1-.4 38.5 7 67.1-10 23.9-24.9 56-35.4 74.4-20 10.3-47 26.2-51 46.2-3.3 15.8 26 55.2 76.1-31.2 22.4-7.4 46.8-16.5 68.4-20.1 18.9 10.2 41 17 55.8 17 25.5 0 28-28.2 17.5-38.7zm-198.1 77.8c5.1-13.7 24.5-29.5 30.4-35-19 30.3-30.4 35.7-30.4 35zm81.6-190.6c7.4 0 6.7 32.1 1.8 40.8-4.4-13.9-4.3-40.8-1.8-40.8zm-24.4 136.6c9.7-16.9 18-37 24.7-54.7 8.3 15.1 18.9 27.2 30.1 35.5-20.8 4.3-38.9 13.1-54.8 19.2zm131.6-5s-5 6-37.3-7.8c35.1-2.6 40.9 5.4 37.3 7.8z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Download Product Images<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a927874 elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"a927874\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.uniquewines.mhttps:\/\/unique.doppelandganger.xyz\/wp-content\/uploads\/2025\/05\/HSM-PRESSKIT.zip\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-file-pdf\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M369.9 97.9L286 14C277 5 264.8-.1 252.1-.1H48C21.5 0 0 21.5 0 48v416c0 26.5 21.5 48 48 48h288c26.5 0 48-21.5 48-48V131.9c0-12.7-5.1-25-14.1-34zM332.1 128H256V51.9l76.1 76.1zM48 464V48h160v104c0 13.3 10.7 24 24 24h104v288H48zm250.2-143.7c-12.2-12-47-8.7-64.4-6.5-17.2-10.5-28.7-25-36.8-46.3 3.9-16.1 10.1-40.6 5.4-56-4.2-26.2-37.8-23.6-42.6-5.9-4.4 16.1-.4 38.5 7 67.1-10 23.9-24.9 56-35.4 74.4-20 10.3-47 26.2-51 46.2-3.3 15.8 26 55.2 76.1-31.2 22.4-7.4 46.8-16.5 68.4-20.1 18.9 10.2 41 17 55.8 17 25.5 0 28-28.2 17.5-38.7zm-198.1 77.8c5.1-13.7 24.5-29.5 30.4-35-19 30.3-30.4 35.7-30.4 35zm81.6-190.6c7.4 0 6.7 32.1 1.8 40.8-4.4-13.9-4.3-40.8-1.8-40.8zm-24.4 136.6c9.7-16.9 18-37 24.7-54.7 8.3 15.1 18.9 27.2 30.1 35.5-20.8 4.3-38.9 13.1-54.8 19.2zm131.6-5s-5 6-37.3-7.8c35.1-2.6 40.9 5.4 37.3 7.8z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Download Presskit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-632f627a\" data-id=\"632f627a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:2,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:50,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;laptop&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce68f53 elementor-widget elementor-widget-image\" data-id=\"ce68f53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2025\/06\/Macon-Villages-683x1024.jpg\" class=\"attachment-large size-large wp-image-5065\" alt=\"\" srcset=\"https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2025\/06\/Macon-Villages-683x1024.jpg 683w, https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2025\/06\/Macon-Villages-200x300.jpg 200w, https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2025\/06\/Macon-Villages-768x1152.jpg 768w, https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2025\/06\/Macon-Villages-1024x1536.jpg 1024w, https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2025\/06\/Macon-Villages-1366x2048.jpg 1366w, https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2025\/06\/Macon-Villages-scaled.jpg 1280w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ef5506b\" data-id=\"ef5506b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:2,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:50,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f3edbff e-con-full elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-parent\" data-id=\"f3edbff\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-889c648 e-con-full e-flex e-con e-child\" data-id=\"889c648\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ea440fb elementor-widget elementor-widget-image\" data-id=\"ea440fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"412\" height=\"449\" data-src=\"https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2025\/05\/cmb2024-grand-gold-medal.png\" class=\"attachment-medium_large size-medium_large wp-image-4527 lazyload\" alt=\"\" data-srcset=\"https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2025\/05\/cmb2024-grand-gold-medal.png 412w, https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2025\/05\/cmb2024-grand-gold-medal-275x300.png 275w\" data-sizes=\"(max-width: 412px) 100vw, 412px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 412px; --smush-placeholder-aspect-ratio: 412\/449;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4ed00fd e-con-full e-flex e-con e-child\" data-id=\"4ed00fd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a762597 elementor-widget elementor-widget-image\" data-id=\"a762597\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"412\" height=\"449\" data-src=\"https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2025\/05\/cmb2024-grand-gold-medal.png\" class=\"attachment-medium_large size-medium_large wp-image-4527 lazyload\" alt=\"\" data-srcset=\"https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2025\/05\/cmb2024-grand-gold-medal.png 412w, https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2025\/05\/cmb2024-grand-gold-medal-275x300.png 275w\" data-sizes=\"(max-width: 412px) 100vw, 412px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 412px; --smush-placeholder-aspect-ratio: 412\/449;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-407b689 e-con-full e-flex e-con e-child\" data-id=\"407b689\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-71faf4e elementor-widget elementor-widget-image\" data-id=\"71faf4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"412\" height=\"449\" data-src=\"https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2025\/05\/cmb2024-grand-gold-medal.png\" class=\"attachment-medium_large size-medium_large wp-image-4527 lazyload\" alt=\"\" data-srcset=\"https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2025\/05\/cmb2024-grand-gold-medal.png 412w, https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2025\/05\/cmb2024-grand-gold-medal-275x300.png 275w\" data-sizes=\"(max-width: 412px) 100vw, 412px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 412px; --smush-placeholder-aspect-ratio: 412\/449;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-21dcb2b9 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"21dcb2b9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-274b17be\" data-id=\"274b17be\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c52ea15 elementor-widget elementor-widget-icon-box\" data-id=\"4c52ea15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tWine Type\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tWhite\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-73199cc4\" data-id=\"73199cc4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-512234c elementor-widget elementor-widget-icon-box\" data-id=\"512234c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAging potential\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t5 years\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-4103097b\" data-id=\"4103097b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69e4863e elementor-widget elementor-widget-icon-box\" data-id=\"69e4863e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAppellation of Origin\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tBurgundy, France\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-5cc25373\" data-id=\"5cc25373\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3611fcb6 elementor-widget elementor-widget-icon-box\" data-id=\"3611fcb6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAlcohol\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t13,0%\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-734e3048 elementor-section-content-middle elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"734e3048\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-51742b3c\" data-id=\"51742b3c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:2,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:50,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a8b0e3a elementor-widget elementor-widget-image\" data-id=\"4a8b0e3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1314\" height=\"1920\" data-src=\"https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2025\/06\/torresella_selezione2-3-scaled.jpg\" class=\"attachment-full size-full wp-image-5016 lazyload\" alt=\"\" data-srcset=\"https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2025\/06\/torresella_selezione2-3-scaled.jpg 1314w, https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2025\/06\/torresella_selezione2-3-205x300.jpg 205w, https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2025\/06\/torresella_selezione2-3-701x1024.jpg 701w, https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2025\/06\/torresella_selezione2-3-768x1122.jpg 768w, https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2025\/06\/torresella_selezione2-3-1051x1536.jpg 1051w, https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2025\/06\/torresella_selezione2-3-1402x2048.jpg 1402w\" data-sizes=\"(max-width: 1314px) 100vw, 1314px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1314px; --smush-placeholder-aspect-ratio: 1314\/1920;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4bccee59\" data-id=\"4bccee59\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-72449305 elementor-widget elementor-widget-heading\" data-id=\"72449305\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pairing<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21af6ca6 elementor-widget elementor-widget-text-editor\" data-id=\"21af6ca6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 1\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>Optimal as an aperitif, it also combines well with both simple and elaborate recipes based on vegetables and fish.<\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Joseph Drouhin Macon Villages The wine&#8217;s color is bright and clear. On the nose, it is floral and fruity. On the palate, it is very frank and direct, as if you were biting into a grape. Fresh and light, with a very pleasant aftertaste. Download Technical Sheet Download Product Images Download Presskit Wine Type White [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4609,"parent":5330,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5548","page","type-page","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Joseph Drouhin Macon Villages The wine\u2019s color is bright and clear. On the nose, it is floral and fruity. On the palate, it is very frank and direct, as if you were biting into a grape. Fresh and light, with a very pleasant aftertaste. Download Technical Sheet Download Product Images Download Presskit Wine Type White\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.uniquewines.mx\/en\/our-brands\/france\/joseph-drouhin\/macon-villages\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Unique Wines M\u00e9xico - Vinos \u00fanicos de todo el mundo a tu alcance.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Macon Villages - Unique Wines M\u00e9xico\" \/>\n\t\t<meta property=\"og:description\" content=\"Joseph Drouhin Macon Villages The wine\u2019s color is bright and clear. On the nose, it is floral and fruity. On the palate, it is very frank and direct, as if you were biting into a grape. Fresh and light, with a very pleasant aftertaste. Download Technical Sheet Download Product Images Download Presskit Wine Type White\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.uniquewines.mx\/en\/our-brands\/france\/joseph-drouhin\/macon-villages\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2026\/02\/cropped-Logo-Unique-wines-Tamano.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2026\/02\/cropped-Logo-Unique-wines-Tamano.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-06-10T19:18:14+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-07-30T08:56:43+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Macon Villages - Unique Wines M\u00e9xico\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Joseph Drouhin Macon Villages The wine\u2019s color is bright and clear. On the nose, it is floral and fruity. On the palate, it is very frank and direct, as if you were biting into a grape. Fresh and light, with a very pleasant aftertaste. Download Technical Sheet Download Product Images Download Presskit Wine Type White\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2026\/02\/cropped-Logo-Unique-wines-Tamano.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.uniquewines.mx\\\/en\\\/our-brands\\\/france\\\/joseph-drouhin\\\/macon-villages\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.uniquewines.mx\\\/en\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.uniquewines.mx\\\/en\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.uniquewines.mx\\\/en\\\/our-brands\\\/#listItem\",\"name\":\"Our Brands\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.uniquewines.mx\\\/en\\\/our-brands\\\/#listItem\",\"position\":2,\"name\":\"Our Brands\",\"item\":\"https:\\\/\\\/www.uniquewines.mx\\\/en\\\/our-brands\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.uniquewines.mx\\\/en\\\/our-brands\\\/france\\\/#listItem\",\"name\":\"France\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.uniquewines.mx\\\/en\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.uniquewines.mx\\\/en\\\/our-brands\\\/france\\\/#listItem\",\"position\":3,\"name\":\"France\",\"item\":\"https:\\\/\\\/www.uniquewines.mx\\\/en\\\/our-brands\\\/france\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.uniquewines.mx\\\/en\\\/our-brands\\\/france\\\/joseph-drouhin\\\/#listItem\",\"name\":\"Joseph Drouhin\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.uniquewines.mx\\\/en\\\/our-brands\\\/#listItem\",\"name\":\"Our Brands\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.uniquewines.mx\\\/en\\\/our-brands\\\/france\\\/joseph-drouhin\\\/#listItem\",\"position\":4,\"name\":\"Joseph Drouhin\",\"item\":\"https:\\\/\\\/www.uniquewines.mx\\\/en\\\/our-brands\\\/france\\\/joseph-drouhin\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.uniquewines.mx\\\/en\\\/our-brands\\\/france\\\/joseph-drouhin\\\/macon-villages\\\/#listItem\",\"name\":\"Macon Villages\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.uniquewines.mx\\\/en\\\/our-brands\\\/france\\\/#listItem\",\"name\":\"France\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.uniquewines.mx\\\/en\\\/our-brands\\\/france\\\/joseph-drouhin\\\/macon-villages\\\/#listItem\",\"position\":5,\"name\":\"Macon Villages\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.uniquewines.mx\\\/en\\\/our-brands\\\/france\\\/joseph-drouhin\\\/#listItem\",\"name\":\"Joseph Drouhin\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.uniquewines.mx\\\/en\\\/#organization\",\"name\":\"Unique Wines M\\u00e9xico\",\"description\":\"Vinos \\u00fanicos de todo el mundo a tu alcance.\",\"url\":\"https:\\\/\\\/www.uniquewines.mx\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.uniquewines.mx\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/cropped-Logo-Unique-wines-Tamano.png\",\"@id\":\"https:\\\/\\\/www.uniquewines.mx\\\/en\\\/our-brands\\\/france\\\/joseph-drouhin\\\/macon-villages\\\/#organizationLogo\",\"width\":1798,\"height\":894},\"image\":{\"@id\":\"https:\\\/\\\/www.uniquewines.mx\\\/en\\\/our-brands\\\/france\\\/joseph-drouhin\\\/macon-villages\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uniquewines.mx\\\/en\\\/our-brands\\\/france\\\/joseph-drouhin\\\/macon-villages\\\/#webpage\",\"url\":\"https:\\\/\\\/www.uniquewines.mx\\\/en\\\/our-brands\\\/france\\\/joseph-drouhin\\\/macon-villages\\\/\",\"name\":\"Macon Villages - Unique Wines M\\u00e9xico\",\"description\":\"Joseph Drouhin Macon Villages The wine\\u2019s color is bright and clear. On the nose, it is floral and fruity. On the palate, it is very frank and direct, as if you were biting into a grape. Fresh and light, with a very pleasant aftertaste. Download Technical Sheet Download Product Images Download Presskit Wine Type White\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uniquewines.mx\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.uniquewines.mx\\\/en\\\/our-brands\\\/france\\\/joseph-drouhin\\\/macon-villages\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.uniquewines.mx\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Everest-Balta-040-scaled-1.jpg\",\"@id\":\"https:\\\/\\\/www.uniquewines.mx\\\/en\\\/our-brands\\\/france\\\/joseph-drouhin\\\/macon-villages\\\/#mainImage\",\"width\":1920,\"height\":1920},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uniquewines.mx\\\/en\\\/our-brands\\\/france\\\/joseph-drouhin\\\/macon-villages\\\/#mainImage\"},\"datePublished\":\"2025-06-10T19:18:14+00:00\",\"dateModified\":\"2025-07-30T08:56:43+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uniquewines.mx\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.uniquewines.mx\\\/en\\\/\",\"name\":\"Unique Wines M\\u00e9xico\",\"description\":\"Vinos \\u00fanicos de todo el mundo a tu alcance.\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.uniquewines.mx\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Macon Villages - Unique Wines M\u00e9xico","description":"Joseph Drouhin Macon Villages The wine\u2019s color is bright and clear. On the nose, it is floral and fruity. On the palate, it is very frank and direct, as if you were biting into a grape. Fresh and light, with a very pleasant aftertaste. Download Technical Sheet Download Product Images Download Presskit Wine Type White","canonical_url":"https:\/\/www.uniquewines.mx\/en\/our-brands\/france\/joseph-drouhin\/macon-villages\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.uniquewines.mx\/en\/our-brands\/france\/joseph-drouhin\/macon-villages\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.uniquewines.mx\/en\/#listItem","position":1,"name":"Home","item":"https:\/\/www.uniquewines.mx\/en\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.uniquewines.mx\/en\/our-brands\/#listItem","name":"Our Brands"}},{"@type":"ListItem","@id":"https:\/\/www.uniquewines.mx\/en\/our-brands\/#listItem","position":2,"name":"Our Brands","item":"https:\/\/www.uniquewines.mx\/en\/our-brands\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.uniquewines.mx\/en\/our-brands\/france\/#listItem","name":"France"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.uniquewines.mx\/en\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.uniquewines.mx\/en\/our-brands\/france\/#listItem","position":3,"name":"France","item":"https:\/\/www.uniquewines.mx\/en\/our-brands\/france\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.uniquewines.mx\/en\/our-brands\/france\/joseph-drouhin\/#listItem","name":"Joseph Drouhin"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.uniquewines.mx\/en\/our-brands\/#listItem","name":"Our Brands"}},{"@type":"ListItem","@id":"https:\/\/www.uniquewines.mx\/en\/our-brands\/france\/joseph-drouhin\/#listItem","position":4,"name":"Joseph Drouhin","item":"https:\/\/www.uniquewines.mx\/en\/our-brands\/france\/joseph-drouhin\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.uniquewines.mx\/en\/our-brands\/france\/joseph-drouhin\/macon-villages\/#listItem","name":"Macon Villages"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.uniquewines.mx\/en\/our-brands\/france\/#listItem","name":"France"}},{"@type":"ListItem","@id":"https:\/\/www.uniquewines.mx\/en\/our-brands\/france\/joseph-drouhin\/macon-villages\/#listItem","position":5,"name":"Macon Villages","previousItem":{"@type":"ListItem","@id":"https:\/\/www.uniquewines.mx\/en\/our-brands\/france\/joseph-drouhin\/#listItem","name":"Joseph Drouhin"}}]},{"@type":"Organization","@id":"https:\/\/www.uniquewines.mx\/en\/#organization","name":"Unique Wines M\u00e9xico","description":"Vinos \u00fanicos de todo el mundo a tu alcance.","url":"https:\/\/www.uniquewines.mx\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2026\/02\/cropped-Logo-Unique-wines-Tamano.png","@id":"https:\/\/www.uniquewines.mx\/en\/our-brands\/france\/joseph-drouhin\/macon-villages\/#organizationLogo","width":1798,"height":894},"image":{"@id":"https:\/\/www.uniquewines.mx\/en\/our-brands\/france\/joseph-drouhin\/macon-villages\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/www.uniquewines.mx\/en\/our-brands\/france\/joseph-drouhin\/macon-villages\/#webpage","url":"https:\/\/www.uniquewines.mx\/en\/our-brands\/france\/joseph-drouhin\/macon-villages\/","name":"Macon Villages - Unique Wines M\u00e9xico","description":"Joseph Drouhin Macon Villages The wine\u2019s color is bright and clear. On the nose, it is floral and fruity. On the palate, it is very frank and direct, as if you were biting into a grape. Fresh and light, with a very pleasant aftertaste. Download Technical Sheet Download Product Images Download Presskit Wine Type White","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.uniquewines.mx\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.uniquewines.mx\/en\/our-brands\/france\/joseph-drouhin\/macon-villages\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2025\/05\/Everest-Balta-040-scaled-1.jpg","@id":"https:\/\/www.uniquewines.mx\/en\/our-brands\/france\/joseph-drouhin\/macon-villages\/#mainImage","width":1920,"height":1920},"primaryImageOfPage":{"@id":"https:\/\/www.uniquewines.mx\/en\/our-brands\/france\/joseph-drouhin\/macon-villages\/#mainImage"},"datePublished":"2025-06-10T19:18:14+00:00","dateModified":"2025-07-30T08:56:43+00:00"},{"@type":"WebSite","@id":"https:\/\/www.uniquewines.mx\/en\/#website","url":"https:\/\/www.uniquewines.mx\/en\/","name":"Unique Wines M\u00e9xico","description":"Vinos \u00fanicos de todo el mundo a tu alcance.","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.uniquewines.mx\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Unique Wines M\u00e9xico - Vinos \u00fanicos de todo el mundo a tu alcance.","og:type":"article","og:title":"Macon Villages - Unique Wines M\u00e9xico","og:description":"Joseph Drouhin Macon Villages The wine\u2019s color is bright and clear. On the nose, it is floral and fruity. On the palate, it is very frank and direct, as if you were biting into a grape. Fresh and light, with a very pleasant aftertaste. Download Technical Sheet Download Product Images Download Presskit Wine Type White","og:url":"https:\/\/www.uniquewines.mx\/en\/our-brands\/france\/joseph-drouhin\/macon-villages\/","og:image":"https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2026\/02\/cropped-Logo-Unique-wines-Tamano.png","og:image:secure_url":"https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2026\/02\/cropped-Logo-Unique-wines-Tamano.png","article:published_time":"2025-06-10T19:18:14+00:00","article:modified_time":"2025-07-30T08:56:43+00:00","twitter:card":"summary_large_image","twitter:title":"Macon Villages - Unique Wines M\u00e9xico","twitter:description":"Joseph Drouhin Macon Villages The wine\u2019s color is bright and clear. On the nose, it is floral and fruity. On the palate, it is very frank and direct, as if you were biting into a grape. Fresh and light, with a very pleasant aftertaste. Download Technical Sheet Download Product Images Download Presskit Wine Type White","twitter:image":"https:\/\/www.uniquewines.mx\/wp-content\/uploads\/2026\/02\/cropped-Logo-Unique-wines-Tamano.png"},"aioseo_meta_data":{"post_id":"5548","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-07-30 08:56:43","updated":"2025-07-30 10:50:06","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.uniquewines.mx\/en\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.uniquewines.mx\/en\/our-brands\/\" title=\"Our Brands\">Our Brands<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.uniquewines.mx\/en\/our-brands\/france\/\" title=\"France\">France<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.uniquewines.mx\/en\/our-brands\/france\/joseph-drouhin\/\" title=\"Joseph Drouhin\">Joseph Drouhin<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMacon Villages\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.uniquewines.mx\/en\/"},{"label":"Our Brands","link":"https:\/\/www.uniquewines.mx\/en\/our-brands\/"},{"label":"France","link":"https:\/\/www.uniquewines.mx\/en\/our-brands\/france\/"},{"label":"Joseph Drouhin","link":"https:\/\/www.uniquewines.mx\/en\/our-brands\/france\/joseph-drouhin\/"},{"label":"Macon Villages","link":"https:\/\/www.uniquewines.mx\/en\/our-brands\/france\/joseph-drouhin\/macon-villages\/"}],"_links":{"self":[{"href":"https:\/\/www.uniquewines.mx\/en\/wp-json\/wp\/v2\/pages\/5548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uniquewines.mx\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.uniquewines.mx\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.uniquewines.mx\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uniquewines.mx\/en\/wp-json\/wp\/v2\/comments?post=5548"}],"version-history":[{"count":2,"href":"https:\/\/www.uniquewines.mx\/en\/wp-json\/wp\/v2\/pages\/5548\/revisions"}],"predecessor-version":[{"id":5551,"href":"https:\/\/www.uniquewines.mx\/en\/wp-json\/wp\/v2\/pages\/5548\/revisions\/5551"}],"up":[{"embeddable":true,"href":"https:\/\/www.uniquewines.mx\/en\/wp-json\/wp\/v2\/pages\/5330"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uniquewines.mx\/en\/wp-json\/wp\/v2\/media\/4609"}],"wp:attachment":[{"href":"https:\/\/www.uniquewines.mx\/en\/wp-json\/wp\/v2\/media?parent=5548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}